{"id":169,"date":"2021-03-22T12:57:56","date_gmt":"2021-03-22T12:57:56","guid":{"rendered":"https:\/\/webs.uab.cat\/pensarlaimagen\/utopies-comunitaries\/"},"modified":"2021-03-22T12:57:56","modified_gmt":"2021-03-22T12:57:56","slug":"utopies-comunitaries","status":"publish","type":"page","link":"https:\/\/webs.uab.cat\/pensarlaimagen\/utopies-comunitaries\/","title":{"rendered":"Utopies comunit\u00e0ries"},"content":{"rendered":"<p class=\"rtejustify\">\u00bfVindr\u00e0 la salvaci\u00f3 de m\u00e9s enll\u00e0 de la muralla, mental, f\u00edsica o on\u00edrica, com intu\u00efa Giovanni Drogo a Il deserto dei Tartari, obrint aix\u00ed un dels camins de la utopia?\u00bfNo vindr\u00e0, perqu\u00e8 no cal i no se l\u2019espera? \u00bfO com la vacuna de la covid, nom\u00e9s ho far\u00e0 pel 50% dels que l\u2019esperen?<\/p>\n<p><em>(Joan Carles Cirera)<\/em><\/p>\n<p><strong><span style=\"color:#993300; \">Maria Gargant\u00e9<\/span><\/strong><br \/>\nDe \u201cLa Rep\u00fablica de Plat\u00f3\u201d d\u2019un jesu\u00efta mataron\u00ed a una utopia ponentina al segle XVIII: connexions amb la ciutat d\u2019avui<br \/>\n<strong><span style=\"color:#993300; \">Oscar Jan\u00e9<\/span><\/strong><br \/>\nQuan les fronteres esdevenen afronteres. Una comparativa entre comunitats latents<\/p>\n<p>\n<strong>Moderen<\/strong><br \/>\n<b>Jos\u00e9 Mar\u00eda Perceval<\/b><br \/>\n<b>Raquel Yafari<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfVindr\u00e0 la salvaci\u00f3 de m\u00e9s enll\u00e0 de la muralla, mental, f\u00edsica o on\u00edrica, com intu\u00efa Giovanni Drogo a Il deserto dei Tartari, obrint aix\u00ed un dels camins de la utopia?\u00bfNo vindr\u00e0, perqu\u00e8 no cal i no se l\u2019espera? \u00bfO com la vacuna de la covid, nom\u00e9s ho far\u00e0 pel 50% dels que l\u2019esperen? (Joan Carles [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-169","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/webs.uab.cat\/pensarlaimagen\/wp-json\/wp\/v2\/pages\/169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webs.uab.cat\/pensarlaimagen\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/webs.uab.cat\/pensarlaimagen\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/webs.uab.cat\/pensarlaimagen\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/webs.uab.cat\/pensarlaimagen\/wp-json\/wp\/v2\/comments?post=169"}],"version-history":[{"count":0,"href":"https:\/\/webs.uab.cat\/pensarlaimagen\/wp-json\/wp\/v2\/pages\/169\/revisions"}],"wp:attachment":[{"href":"https:\/\/webs.uab.cat\/pensarlaimagen\/wp-json\/wp\/v2\/media?parent=169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}